{"id":10791,"date":"2025-10-31T13:02:04","date_gmt":"2025-10-31T12:02:04","guid":{"rendered":"https:\/\/www.conect.at\/?page_id=10791"},"modified":"2025-10-31T13:02:04","modified_gmt":"2025-10-31T12:02:04","slug":"anmeldung-zu-cpre-advanced-level-modul-reagile","status":"publish","type":"page","link":"https:\/\/www.conect.at\/en\/anmeldung-zu-cpre-advanced-level-modul-reagile","title":{"rendered":"Anmeldung zu CPRE Advanced Level \u2013 Modul RE@Agile"},"content":{"rendered":"<p><strong>Teilnahmegeb\u00fchr:<\/strong><br \/>\nStandardpreis:\u2001\u20ac 1.570,\u2013<\/p>\n<p><strong>Pr\u00fcfungsgeb\u00fchren:<\/strong><\/p>\n<ul>\n<li>CPRE Advanced Level Modul Re@Agile \u2013 Practitioner: \u20ac\u00a0280,\u2013<\/li>\n<li>CPRE Advanced Level Modul Re@Agile \u2013 Specialist: \u20ac\u00a0460,\u2013<\/li>\n<\/ul>\n<p>Alle Preise zuz\u00fcgl 20 % MWSt<\/p>\n<div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-10790\"><form id=\"wpforms-form-10790\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"10790\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/10791\" data-token=\"6876edcf72ca8f431c690a646199d904\" data-token-time=\"1784111321\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-hidden\" id=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-10790-field_21-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"21\"><label class=\"wpforms-field-label\" for=\"wpforms-10790-field_21\">Name Seminar:<\/label><input type=\"text\" id=\"wpforms-10790-field_21\" class=\"wpforms-field-medium\" name=\"wpforms[fields][21]\" value=\"CPRE Advanced Level \u2013 Modul RE@Agile\" aria-errormessage=\"wpforms-10790-field_21-error\" ><\/div><div id=\"wpforms-10790-field_22-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"22\"><label class=\"wpforms-field-label\" for=\"wpforms-10790-field_22\">Datum Seminar: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-10790-field_22\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][22]\" aria-errormessage=\"wpforms-10790-field_22-error\" required><\/div><div id=\"wpforms-10790-field_24-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"24\"><label class=\"wpforms-field-label\" for=\"wpforms-10790-field_24\">Aktionscode<\/label><input type=\"text\" id=\"wpforms-10790-field_24\" class=\"wpforms-field-medium\" name=\"wpforms[fields][24]\" aria-errormessage=\"wpforms-10790-field_24-error\" ><\/div><div id=\"wpforms-10790-field_2-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-10790-field_2\">Anrede <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-10790-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" required=\"required\"><option value=\"Herr\" >Herr<\/option><option value=\"Frau\" >Frau<\/option><option value=\"Sonstiges\" >Sonstiges<\/option><\/select><\/div><div id=\"wpforms-10790-field_3-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-10790-field_3\">Titel<\/label><input type=\"text\" id=\"wpforms-10790-field_3\" class=\"wpforms-field-medium\" name=\"wpforms[fields][3]\" aria-errormessage=\"wpforms-10790-field_3-error\" ><\/div><div id=\"wpforms-10790-field_4-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-10790-field_4\">Vorname <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-10790-field_4\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][4]\" aria-errormessage=\"wpforms-10790-field_4-error\" required><\/div><div id=\"wpforms-10790-field_5-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-10790-field_5\">Nachname <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-10790-field_5\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][5]\" aria-errormessage=\"wpforms-10790-field_5-error\" required><\/div><div id=\"wpforms-10790-field_6-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-10790-field_6\">Firma<\/label><input type=\"text\" id=\"wpforms-10790-field_6\" class=\"wpforms-field-medium\" name=\"wpforms[fields][6]\" aria-errormessage=\"wpforms-10790-field_6-error\" ><\/div><div id=\"wpforms-10790-field_7-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-10790-field_7\">Funktion<\/label><input type=\"text\" id=\"wpforms-10790-field_7\" class=\"wpforms-field-medium\" name=\"wpforms[fields][7]\" aria-errormessage=\"wpforms-10790-field_7-error\" ><\/div><div id=\"wpforms-10790-field_8-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-10790-field_8\">Fachbereich<\/label><input type=\"text\" id=\"wpforms-10790-field_8\" class=\"wpforms-field-medium\" name=\"wpforms[fields][8]\" aria-errormessage=\"wpforms-10790-field_8-error\" ><\/div><div id=\"wpforms-10790-field_25-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"25\"><label class=\"wpforms-field-label\" for=\"wpforms-10790-field_25\">UID<\/label><input type=\"text\" id=\"wpforms-10790-field_25\" class=\"wpforms-field-medium\" name=\"wpforms[fields][25]\" aria-errormessage=\"wpforms-10790-field_25-error\" ><\/div><div id=\"wpforms-10790-field_9-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-10790-field_9\">Stra\u00dfe <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-10790-field_9\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][9]\" aria-errormessage=\"wpforms-10790-field_9-error\" required><\/div><div id=\"wpforms-10790-field_23-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"23\"><label class=\"wpforms-field-label\" for=\"wpforms-10790-field_23\">Rechnungsadresse<\/label><input type=\"text\" id=\"wpforms-10790-field_23\" class=\"wpforms-field-medium\" name=\"wpforms[fields][23]\" aria-errormessage=\"wpforms-10790-field_23-error\" ><\/div><div id=\"wpforms-10790-field_17-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"17\"><label class=\"wpforms-field-label\" for=\"wpforms-10790-field_17\">PLZ <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"number\" id=\"wpforms-10790-field_17\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][17]\" aria-errormessage=\"wpforms-10790-field_17-error\" required><\/div><div id=\"wpforms-10790-field_11-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"11\"><label class=\"wpforms-field-label\" for=\"wpforms-10790-field_11\">Ort <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-10790-field_11\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][11]\" aria-errormessage=\"wpforms-10790-field_11-error\" required><\/div><div id=\"wpforms-10790-field_12-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"12\"><label class=\"wpforms-field-label\" for=\"wpforms-10790-field_12\">Land<\/label><input type=\"text\" id=\"wpforms-10790-field_12\" class=\"wpforms-field-medium\" name=\"wpforms[fields][12]\" aria-errormessage=\"wpforms-10790-field_12-error\" ><\/div>\t\t<div id=\"wpforms-10790-field_1-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"1\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-10790-field_1\" >Titel Telefon Stra\u00dfe<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-10790-field_1\" class=\"wpforms-field-medium\" name=\"wpforms[fields][1]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-10790-field_13-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"13\"><label class=\"wpforms-field-label\" for=\"wpforms-10790-field_13\">Telefon <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-10790-field_13\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][13]\" aria-errormessage=\"wpforms-10790-field_13-error\" required><\/div><div id=\"wpforms-10790-field_15-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"15\"><label class=\"wpforms-field-label\" for=\"wpforms-10790-field_15\">Mobiltelefon<\/label><input type=\"text\" id=\"wpforms-10790-field_15\" class=\"wpforms-field-medium\" name=\"wpforms[fields][15]\" aria-errormessage=\"wpforms-10790-field_15-error\" ><\/div><div id=\"wpforms-10790-field_16-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"16\"><label class=\"wpforms-field-label\" for=\"wpforms-10790-field_16\">E-Mail-Adresse <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-10790-field_16\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][16]\" spellcheck=\"false\" aria-errormessage=\"wpforms-10790-field_16-error\" required><\/div><div id=\"wpforms-10790-field_19-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"19\"><fieldset><legend class=\"wpforms-field-label\">Bitte best\u00e4tigen: <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-10790-field_19\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-10790-field_19_1\" name=\"wpforms[fields][19][]\" value=\"Bitte best\u00e4tigen Sie hier die kostenfreie\/kostenpflichtige Teilnahme an der Veranstaltung und die kostenfreie Mitgliedschaft in der Con.ect Community. Dadurch beauftragen Sie uns mit der dauerhaften Speicherung von Teilnahme-Best\u00e4tigungen, Zertifikaten, Teilnahmelisten, Fotos, Dokumenten von Veranstaltungen und erhalten regelm\u00e4\u00dfig unseren Newsletter und Post Aussendungen. (PDF)\" aria-errormessage=\"wpforms-10790-field_19_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-10790-field_19_1\">Bitte best\u00e4tigen Sie hier die kostenfreie\/kostenpflichtige Teilnahme an der Veranstaltung und die kostenfreie Mitgliedschaft in der Con.ect Community. Dadurch beauftragen Sie uns mit der dauerhaften Speicherung von Teilnahme-Best\u00e4tigungen, Zertifikaten, Teilnahmelisten, Fotos, Dokumenten von Veranstaltungen und erhalten regelm\u00e4\u00dfig unseren Newsletter und Post Aussendungen. (PDF)<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-10790-field_19_2\" name=\"wpforms[fields][19][]\" value=\"Es gelten unsere AGBs f\u00fcr Veranstaltungen\" aria-errormessage=\"wpforms-10790-field_19_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-10790-field_19_2\">Es gelten unsere AGBs f\u00fcr Veranstaltungen<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-10790-field_19_3\" name=\"wpforms[fields][19][]\" value=\"Ich stimme den Con.ect Datenschutzbestimmungen \/ des Future Network zu\" aria-errormessage=\"wpforms-10790-field_19_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-10790-field_19_3\">Ich stimme den Con.ect Datenschutzbestimmungen \/ des Future Network zu<\/label><\/li><\/ul><\/fieldset><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-10790-field_1-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-10790-field_1-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-10790-field_1-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"10790\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/www.conect.at\/en\/wp-json\/wp\/v2\/pages\/10791\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-10790\" class=\"wpforms-submit\" data-alt-text=\"Wird gesendet\u00a0\u2026\" data-submit-text=\"anmelden\" aria-live=\"assertive\" value=\"wpforms-submit\">anmelden<\/button><img src=\"https:\/\/www.conect.at\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\n","protected":false},"excerpt":{"rendered":"<p>Teilnahmegeb\u00fchr: Standardpreis:\u2001\u20ac 1.570,\u2013 Pr\u00fcfungsgeb\u00fchren: CPRE Advanced Level Modul Re@Agile \u2013 Practitioner: \u20ac\u00a0280,\u2013 CPRE Advanced Level Modul Re@Agile \u2013 Specialist: \u20ac\u00a0460,\u2013 Alle Preise zuz\u00fcgl 20 % MWSt<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.conect.at\/en\/wp-json\/wp\/v2\/pages\/10791"}],"collection":[{"href":"https:\/\/www.conect.at\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.conect.at\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.conect.at\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.conect.at\/en\/wp-json\/wp\/v2\/comments?post=10791"}],"version-history":[{"count":0,"href":"https:\/\/www.conect.at\/en\/wp-json\/wp\/v2\/pages\/10791\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.conect.at\/en\/wp-json\/wp\/v2\/media?parent=10791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}